{"id":4359,"date":"2021-03-28T09:59:31","date_gmt":"2021-03-28T07:59:31","guid":{"rendered":"https:\/\/madridtravelprivatetours.com\/tour-operateurs\/dia-completo-en-madrid\/"},"modified":"2025-12-09T18:54:27","modified_gmt":"2025-12-09T17:54:27","slug":"offre-dune-journee-complete-a-madrid","status":"publish","type":"page","link":"https:\/\/madridtravelprivatetours.com\/fr\/tour-operateurs\/offre-dune-journee-complete-a-madrid\/","title":{"rendered":"OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4359\" class=\"elementor elementor-4359 elementor-877\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7951b915 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7951b915\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b4b16b8\" data-id=\"b4b16b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1f117dcc elementor-widget elementor-widget-heading\" data-id=\"1f117dcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tour-Op\u00e9rateurs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16d7702f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"16d7702f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31fa9d58 elementor-widget elementor-widget-heading\" data-id=\"31fa9d58\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-226e882 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"226e882\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-734566fa\" data-id=\"734566fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c5b6d3 elementor-widget elementor-widget-heading\" data-id=\"6c5b6d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nous vous proposons plusieurs activit\u00e9s de 2 heures que vous pouvez combiner en fonction des int\u00e9r\u00eats de votre client:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79bb91a9 elementor-widget elementor-widget-text-editor\" data-id=\"79bb91a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre visite de journ\u00e9e compl\u00e8te \u00e0 Madrid a une dur\u00e9e de 7 heures.<\/p><h2>Balade dans le Vieux Madrid: 2 heures<\/h2><p>Madrid garde comme un tr\u00e9sor son quartier historique, le Madrid des Autrichiens. Ce quartier abrite des \u00e9difices qui furent construits sous le r\u00e8gne de la maison d\u2019Autriche, d\u2019o\u00f9 son nom. Nous allons d\u00e9couvrir ses lieux les plus embl\u00e9matiques : La Plaza de Oriente, le Palais Royal (ext\u00e9rieur), la Cath\u00e9drale de la Almudena, le march\u00e9 de San Miguel, la Plaza Mayor et la Puerta del Sol. Le quartier est plein de petites ruelles et de tr\u00e9sors cach\u00e9s.<\/p><p>Pendant la visite, nous vous parlerons des origines arabes de Madrid, de son \u00e9volution historique jusqu\u2019\u00e0 devenir la capitale du royaume en 1571, des particularit\u00e9s des madril\u00e8nes, ainsi que de son ambiance accueillante et cosmopolite.<\/p><p>Cette visite est l\u2019une des plus demand\u00e9es par nos clients.<\/p><h2>Visite panoramique en v\u00e9hicule priv\u00e9: 2 heures<\/h2><p>Cette visite offre un aper\u00e7u complet de la ville et donne une id\u00e9e g\u00e9n\u00e9rale de ses quartiers les plus repr\u00e9sentatifs : le Madrid du XVIIIe si\u00e8cle avec ses grands mus\u00e9es et ses belles fontaines mythologiques, le parc du Retiro, les boutiques de luxe du quartier de Salamanca, les ar\u00e8nes Las Ventas, le Paseo de la Castellana, la zone financi\u00e8re, le stade du Real Madrid et l\u2019embl\u00e9matique Gran V\u00eda avec ses b\u00e2timents du d\u00e9but du XXe si\u00e8cle.<\/p><h5><strong>Visite d\u2019un monument au choix : Le Palais Royal, le mus\u00e9e du Prado, le mus\u00e9e Reina Sofia, le stade Santiago Bernabeu, etc.<\/strong><\/h5><h2>Le Palais Royal: 2 heures<\/h2><p>Le Palais Royal de Madrid est le plus grand d\u2019Europe occidentale. Ses plus de 3 000 pi\u00e8ces ont \u00e9t\u00e9 le sc\u00e9nario de notre Histoire depuis des si\u00e8cles. C\u2019\u00e9tait la r\u00e9sidence principale de la famille royale espagnole de 1764 \u00e0 1931. C\u2019est un mus\u00e9e vivant qui est encore utilis\u00e9 aujourd\u2019hui pour les actes officiels de l\u2019\u00c9tat espagnol, \u00e9tant l\u2019une des rares r\u00e9sidences officielles des chefs d\u2019\u00c9tat ouvertes au public.<\/p><p>Nous verrons leurs salles plus belles, salons officiels et l\u2019Armurerie royale. Notre visite guid\u00e9e vous montrera son histoire fascinante, son art et ses curiosit\u00e9s.<\/p><h2>Le Mus\u00e9e du Prado: 2 heures<\/h2><p>Le Prado c\u2019est l\u2019un de plus beaux mus\u00e9es au monde. Ses salles ne nous montrent pratiquement que des chefs-d\u2019\u0153uvre, notamment des \u00e9coles Espagnoles, Italiennes et Flamandes. Inaugur\u00e9e en 1819, une grande partie de ses \u0153uvres proviennent des Collections royales. Dans cette visite on vous propose de d\u00e9couvrir d\u2019une mani\u00e8re didactique et dynamique, les \u0153uvres majeures des grands peintres espagnols\u00a0: Vel\u00e1zquez, Goya, et le Greco. \u00ab\u00a0Les Menines\u00a0\u00bb, \u00ab\u00a0Les Fileuses\u00a0\u00bb de Vel\u00e1zquez, \u00ab\u00a0Les Fusillades de 3 Mai\u00a0\u00bb, \u00ab\u00a0Les Peintures Noires\u00a0\u00bb de Goya, \u00ab\u00a0Le Monsieur \u00e1 la main \u00e1 sa poitrine\u00a0\u00bb du Greco, o\u00f9 \u00ab\u00a0Le Jardins de D\u00e9lices\u00a0\u00bb de J\u00e9r\u00f4me Bosch, font partie de peintures superbes \u00e0 ne pas manquer.<\/p><h2>Le Mus\u00e9e Reina Sof\u00eda: 2 heures<\/h2><p>Il est l\u2019un des trois mus\u00e9es plus importants de la Promenade de l\u2019Art \u00e0 Madrid. Le mus\u00e9e nous offre, \u00e0 travers sa collection permanente, une vision compl\u00e8te du panorama artistique espagnol du XXe si\u00e8cle. Les \u0153uvres de Picasso, Dal\u00ed et Mir\u00f3 sont remarquables. L\u2019\u0153uvre la plus embl\u00e9matique de ce mus\u00e9e c\u2019est \u00ab\u00a0Le Guernica\u00a0\u00bb de Picasso, peint pendant la guerre civile espagnole.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b54bc30\" data-id=\"2b54bc30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a910c0c elementor-widget elementor-widget-image\" data-id=\"2a910c0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/IMG_20200515_090228.jpg\" class=\"attachment-large size-large wp-image-1338\" alt=\"\" srcset=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/IMG_20200515_090228.jpg 1000w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/IMG_20200515_090228-300x225.jpg 300w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/IMG_20200515_090228-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7611125 elementor-widget elementor-widget-image\" data-id=\"7611125\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/cibeles-1024x682.jpg\" class=\"attachment-large size-large wp-image-2299\" alt=\"\" srcset=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/cibeles-1024x682.jpg 1024w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/cibeles-300x200.jpg 300w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/cibeles-768x512.jpg 768w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/cibeles.jpg 1400w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ba3893 elementor-widget elementor-widget-image\" data-id=\"1ba3893\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/IMG_6231-1024x768.jpeg\" class=\"attachment-large size-large wp-image-4362\" alt=\"\" srcset=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/IMG_6231-1024x768.jpeg 1024w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/IMG_6231-300x225.jpeg 300w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/IMG_6231-768x576.jpeg 768w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/IMG_6231-1536x1152.jpeg 1536w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/IMG_6231-2048x1536.jpeg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3cd67ff elementor-widget elementor-widget-image\" data-id=\"3cd67ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210221_113527-1-1024x768.jpg\" class=\"attachment-large size-large wp-image-4367\" alt=\"\" srcset=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210221_113527-1-1024x768.jpg 1024w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210221_113527-1-300x225.jpg 300w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210221_113527-1-768x576.jpg 768w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210221_113527-1-1536x1152.jpg 1536w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210221_113527-1-2048x1536.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a7610c4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a7610c4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c0d7b8c\" data-id=\"c0d7b8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5cd78b22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5cd78b22\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5ead3b2f\" data-id=\"5ead3b2f\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ef566f3 elementor-widget elementor-widget-heading\" data-id=\"3ef566f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dur\u00e9e: 7 heures<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-278fa578 elementor-widget elementor-widget-heading\" data-id=\"278fa578\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tarif: 535\u20ac + les billets d'acc\u00e8es des mus\u00e9es.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d07d32 elementor-widget elementor-widget-text-editor\" data-id=\"3d07d32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tarif par visite<\/p><div id=\"ts-body\"><div class=\"css-52 ts-pivot-container\"><div id=\"ContentContainer\"><div><div><div role=\"tabpanel\" aria-labelledby=\"Pivot2-Tab0\"><div class=\"ts-lookup-pivot\"><div id=\"Lookup\" class=\"ts-pivot-lookup-component\"><div class=\"ms-Grid ts-grid\"><div class=\"ms-Grid-row\"><div class=\"ts-textfield-container ts-larger-font\" lang=\"fr\"><div class=\"ts-alignment-view-container\"><div id=\"ts-alignment-view-idtgt\" class=\"ts-alignment-view ms-font-m ts-alignment-view-tgt ts-ltr-left-zero\" tabindex=\"0\" aria-hidden=\"false\"><div role=\"label\"><span id=\"tgtAlignment_0\" class=\"ts-alignment-element\" data-is-focusable=\"true\">De<\/span> 1\u00a0<span id=\"tgtAlignment_2\" class=\"ts-alignment-element\" data-is-focusable=\"true\">\u00e0<\/span> 7\u00a0<span id=\"tgtAlignment_4\" class=\"ts-alignment-element-highlighted\" data-is-focusable=\"true\">personnes<\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19cfb75a elementor-widget elementor-widget-heading\" data-id=\"19cfb75a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inclus:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c580773 elementor-widget elementor-widget-text-editor\" data-id=\"5c580773\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p>Notre tarif comme votre guide-conf\u00e9rencier priv\u00e9<\/p><\/li><li><p>Les billets des monuments :<\/p><ul><li><p>Palais Royal : 20\u20ac<\/p><\/li><li><p>Mus\u00e9e du Prado : 15\u20ac<\/p><\/li><li><p>Mus\u00e9e Reina Sofia : 12\u20ac<\/p><\/li><li><p>Stade Santiago Bernabeu : 35\u20ac<\/p><\/li><\/ul><\/li><li><p>Imp\u00f4ts<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee3c2ee elementor-widget elementor-widget-heading\" data-id=\"ee3c2ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Non inclus:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0b5f4c elementor-widget elementor-widget-text-editor\" data-id=\"f0b5f4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><p>Le transport.<br \/>Si vous le souhaitez, nous pouvons g\u00e9rer la location du transport priv\u00e9 avec chauffeur sans frais suppl\u00e9mentaires.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6bac23b2\" data-id=\"6bac23b2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fb928e9 elementor-widget elementor-widget-heading\" data-id=\"3fb928e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Programme<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59e6ef1c elementor-widget elementor-widget-text-editor\" data-id=\"59e6ef1c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le-voil\u00e9 notre combinaison la plus demand\u00e9e\u00a0:<\/p><p>AM (4 Heures) :<\/p><p>Le Palais Royal et Balade dans le Vieux Madrid<\/p><p>1 heure de temps libre pour d\u00e9jeuner<\/p><p>PM (2 Heures):<\/p><p>Tour panoramique en v\u00e9hicule priv\u00e9 ou visite du mus\u00e9e du Prado.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-514b7fbf\" data-id=\"514b7fbf\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e00dfdb elementor-widget elementor-widget-heading\" data-id=\"6e00dfdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Point de rendez-vous <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5cca8fbc elementor-widget elementor-widget-text-editor\" data-id=\"5cca8fbc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 votre H\u00f4tel<\/p><p>Remarque : Si l\u2019h\u00f4tel n\u2019est pas en centre-ville, un suppl\u00e9ment de taxi sera ajout\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bcbeed8 elementor-widget elementor-widget-button\" data-id=\"2bcbeed8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#reserva\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9servez ici <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-115a35c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"115a35c1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-354c42c6\" data-id=\"354c42c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bdaa93b elementor-widget elementor-widget-text-editor\" data-id=\"1bdaa93b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ceci est notre itin\u00e9raire sugg\u00e9r\u00e9. <br \/>N\u2019h\u00e9sitez pas \u00e0 nous contacter pour un tour SUR-MESURE.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23afbb15 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23afbb15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2adcae87\" data-id=\"2adcae87\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44416e4 elementor-widget elementor-widget-heading\" data-id=\"44416e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quelques photos de la visite<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bfc51f4 elementor-widget elementor-widget-gallery\" data-id=\"1bfc51f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_layout&quot;:&quot;justified&quot;,&quot;ideal_row_height&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:294,&quot;sizes&quot;:[]},&quot;gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:2,&quot;sizes&quot;:[]},&quot;lazyload&quot;:&quot;yes&quot;,&quot;ideal_row_height_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;ideal_row_height_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;link_to&quot;:&quot;file&quot;,&quot;overlay_background&quot;:&quot;yes&quot;,&quot;content_hover_animation&quot;:&quot;fade-in&quot;}\" data-widget_type=\"gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-gallery__container\">\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.0..jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"Oso y el Madro\u00f1o\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg4MywidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzAzXC9WSVNJVEExLjAuLmpwZWciLCJzbGlkZXNob3ciOiIxYmZjNTFmNCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.0.-768x576.jpeg\" data-width=\"768\" data-height=\"576\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"VISITA1.1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg4NSwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzAzXC9WSVNJVEExLjEuanBnIiwic2xpZGVzaG93IjoiMWJmYzUxZjQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.1-768x576.jpg\" data-width=\"768\" data-height=\"576\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"VISITA1.2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg4NiwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzAzXC9WSVNJVEExLjIuanBnIiwic2xpZGVzaG93IjoiMWJmYzUxZjQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.2-768x576.jpg\" data-width=\"768\" data-height=\"576\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.3.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"VISITA1.3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg4NywidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzAzXC9WSVNJVEExLjMuanBlZyIsInNsaWRlc2hvdyI6IjFiZmM1MWY0In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.3-768x576.jpeg\" data-width=\"768\" data-height=\"576\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.5.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"VISITA1.5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mzg4OSwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzAzXC9WSVNJVEExLjUuanBnIiwic2xpZGVzaG93IjoiMWJmYzUxZjQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/03\/VISITA1.5-768x576.jpg\" data-width=\"768\" data-height=\"576\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/20191222_120500-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"20191222_120500\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDM2NCwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC8yMDE5MTIyMl8xMjA1MDAtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjFiZmM1MWY0In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/20191222_120500-768x1365.jpg\" data-width=\"768\" data-height=\"1365\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/AdobeStock_208143177-scaled.jpeg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"Madrid\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDM2NSwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC9BZG9iZVN0b2NrXzIwODE0MzE3Ny1zY2FsZWQuanBlZyIsInNsaWRlc2hvdyI6IjFiZmM1MWY0In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/AdobeStock_208143177-768x513.jpeg\" data-width=\"768\" data-height=\"513\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/20170228_141402-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"20170228_141402\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDM2NiwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC8yMDE3MDIyOF8xNDE0MDItc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjFiZmM1MWY0In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/20170228_141402-768x432.jpg\" data-width=\"768\" data-height=\"432\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/ALMUDENAjpg-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"ALMUDENAjpg\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMSwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC9BTE1VREVOQWpwZy1zY2FsZWQuanBnIiwic2xpZGVzaG93IjoiMWJmYzUxZjQifQ%3D%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/ALMUDENAjpg-768x576.jpg\" data-width=\"768\" data-height=\"576\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/20190912_155339_001-2-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"20190912_155339_001 (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyMiwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC8yMDE5MDkxMl8xNTUzMzlfMDAxLTItc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjFiZmM1MWY0In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/20190912_155339_001-2-768x432.jpg\" data-width=\"768\" data-height=\"432\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210424_201111-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"IMG_20210424_201111\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNCwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC9JTUdfMjAyMTA0MjRfMjAxMTExLXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIxYmZjNTFmNCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210424_201111-768x1024.jpg\" data-width=\"768\" data-height=\"1024\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/3angels.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"3angels\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNSwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC8zYW5nZWxzLmpwZyIsInNsaWRlc2hvdyI6IjFiZmM1MWY0In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/3angels-768x432.jpg\" data-width=\"768\" data-height=\"432\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20200522_083448-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"IMG_20200522_083448\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjMyNiwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC9JTUdfMjAyMDA1MjJfMDgzNDQ4LXNjYWxlZC5qcGciLCJzbGlkZXNob3ciOiIxYmZjNTFmNCJ9\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20200522_083448-768x576.jpg\" data-width=\"768\" data-height=\"576\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"e-gallery-item elementor-gallery-item elementor-animated-content\" href=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210501_205638-1-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"1bfc51f4\" data-elementor-lightbox-title=\"IMG_20210501_205638 (1)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6NDM2OCwidXJsIjoiaHR0cHM6XC9cL21hZHJpZHRyYXZlbHByaXZhdGV0b3Vycy5jb21cL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjFcLzA1XC9JTUdfMjAyMTA1MDFfMjA1NjM4LTEtc2NhbGVkLmpwZyIsInNsaWRlc2hvdyI6IjFiZmM1MWY0In0%3D\">\n\t\t\t\t\t<div class=\"e-gallery-image elementor-gallery-item__image\" data-thumbnail=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/05\/IMG_20210501_205638-1-768x576.jpg\" data-width=\"768\" data-height=\"576\" aria-label=\"\" role=\"img\" ><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-gallery-item__overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf77b19 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf77b19\" data-element_type=\"section\" data-e-type=\"section\" id=\"reserva\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63747cd\" data-id=\"63747cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63ecc57 elementor-widget elementor-widget-heading\" data-id=\"63ecc57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9servez votre visite<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d043d9a elementor-widget elementor-widget-text-editor\" data-id=\"d043d9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous avons la meilleure EXP\u00c9RIENCE pour vous<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3726770 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"3726770\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\" aria-label=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"4359\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"3726770\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID - Madrid Travel Private Tours\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"4359\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tNom et pr\u00e9nom\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tEmail\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-message\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tQue souhaitez-vous visiter?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_de6c80b elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_de6c80b]\" id=\"form-field-field_de6c80b\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-field_de6c80b\">J\u2019ai lu et j\u2019accepte la <a href=\" https:\/\/madridtravelprivatetours.com\/fr\/politique-de-confidentialite\/\" target=\"_blank\" rel=\"noreferrer noopener\">politique de confidentialit\u00e9<\/a><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">ENVOYER<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-df01c47\" data-id=\"df01c47\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-172743f elementor-widget elementor-widget-image\" data-id=\"172743f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/02\/las-dos.jpg\" class=\"attachment-large size-large wp-image-3346\" alt=\"\" srcset=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/02\/las-dos.jpg 1000w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/02\/las-dos-300x225.jpg 300w, https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/02\/las-dos-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d783303 elementor-position-inline-start elementor-view-stacked elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"d783303\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/wa.link\/alini4\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"(+34) 627 42 58 55  - Mariluz\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/wa.link\/alini4\" target=\"_blank\" >\n\t\t\t\t\t\t\t(+34) 627 42 58 55  - Mariluz\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46164b0 elementor-position-inline-start elementor-view-stacked elementor-shape-circle elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"46164b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/wa.link\/6idw8o\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\" (+34) 609 14 05 45  - Jacqueline\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-whatsapp\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/wa.link\/6idw8o\" target=\"_blank\" >\n\t\t\t\t\t\t\t (+34) 609 14 05 45  - Jacqueline\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tour-Op\u00e9rateurs OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID Nous vous proposons plusieurs activit\u00e9s de 2 heures que vous pouvez combiner en fonction des int\u00e9r\u00eats de votre client: Notre visite de journ\u00e9e compl\u00e8te \u00e0 Madrid a une dur\u00e9e de 7 heures. Balade dans le Vieux Madrid: 2 heures Madrid garde comme un tr\u00e9sor son quartier historique, le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":3967,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4359","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID - Madrid Travel Private Tours<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID - Madrid Travel Private Tours\" \/>\n<meta property=\"og:description\" content=\"Tour-Op\u00e9rateurs OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID Nous vous proposons plusieurs activit\u00e9s de 2 heures que vous pouvez combiner en fonction des int\u00e9r\u00eats de votre client: Notre visite de journ\u00e9e compl\u00e8te \u00e0 Madrid a une dur\u00e9e de 7 heures. Balade dans le Vieux Madrid: 2 heures Madrid garde comme un tr\u00e9sor son quartier historique, le [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Madrid Travel Private Tours\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T17:54:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/IMG_20200515_090228.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/agencias\\\/dia-completo-en-madrid\\\/\",\"url\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/agencias\\\/dia-completo-en-madrid\\\/\",\"name\":\"OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID - Madrid Travel Private Tours\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/agencias\\\/dia-completo-en-madrid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/agencias\\\/dia-completo-en-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG_20200515_090228.jpg\",\"datePublished\":\"2021-03-28T07:59:31+00:00\",\"dateModified\":\"2025-12-09T17:54:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/agencias\\\/dia-completo-en-madrid\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/madridtravelprivatetours.com\\\/agencias\\\/dia-completo-en-madrid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/agencias\\\/dia-completo-en-madrid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG_20200515_090228.jpg\",\"contentUrl\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/IMG_20200515_090228.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/agencias\\\/dia-completo-en-madrid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"INICIO\",\"item\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TOUR OP\u00c9RATEURS\",\"item\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/agencias\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/#website\",\"url\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/\",\"name\":\"Madrid Travel Private Tours\",\"description\":\"Ofrecemos visitas guiadas privadas en Madrid y alrededores\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/madridtravelprivatetours.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID - Madrid Travel Private Tours","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/","og_locale":"fr_FR","og_type":"article","og_title":"OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID - Madrid Travel Private Tours","og_description":"Tour-Op\u00e9rateurs OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID Nous vous proposons plusieurs activit\u00e9s de 2 heures que vous pouvez combiner en fonction des int\u00e9r\u00eats de votre client: Notre visite de journ\u00e9e compl\u00e8te \u00e0 Madrid a une dur\u00e9e de 7 heures. Balade dans le Vieux Madrid: 2 heures Madrid garde comme un tr\u00e9sor son quartier historique, le [&hellip;]","og_url":"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/","og_site_name":"Madrid Travel Private Tours","article_modified_time":"2025-12-09T17:54:27+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/IMG_20200515_090228.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/","url":"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/","name":"OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID - Madrid Travel Private Tours","isPartOf":{"@id":"https:\/\/madridtravelprivatetours.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/#primaryimage"},"image":{"@id":"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/IMG_20200515_090228.jpg","datePublished":"2021-03-28T07:59:31+00:00","dateModified":"2025-12-09T17:54:27+00:00","breadcrumb":{"@id":"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/#primaryimage","url":"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/IMG_20200515_090228.jpg","contentUrl":"https:\/\/madridtravelprivatetours.com\/wp-content\/uploads\/2021\/04\/IMG_20200515_090228.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/madridtravelprivatetours.com\/agencias\/dia-completo-en-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"INICIO","item":"https:\/\/madridtravelprivatetours.com\/"},{"@type":"ListItem","position":2,"name":"TOUR OP\u00c9RATEURS","item":"https:\/\/madridtravelprivatetours.com\/agencias\/"},{"@type":"ListItem","position":3,"name":"OFFRE D\u2019UNE JOURN\u00c9E COMPL\u00c8TE \u00c0 MADRID"}]},{"@type":"WebSite","@id":"https:\/\/madridtravelprivatetours.com\/#website","url":"https:\/\/madridtravelprivatetours.com\/","name":"Madrid Travel Private Tours","description":"Ofrecemos visitas guiadas privadas en Madrid y alrededores","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/madridtravelprivatetours.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/madridtravelprivatetours.com\/fr\/wp-json\/wp\/v2\/pages\/4359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/madridtravelprivatetours.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/madridtravelprivatetours.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/madridtravelprivatetours.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/madridtravelprivatetours.com\/fr\/wp-json\/wp\/v2\/comments?post=4359"}],"version-history":[{"count":58,"href":"https:\/\/madridtravelprivatetours.com\/fr\/wp-json\/wp\/v2\/pages\/4359\/revisions"}],"predecessor-version":[{"id":12352,"href":"https:\/\/madridtravelprivatetours.com\/fr\/wp-json\/wp\/v2\/pages\/4359\/revisions\/12352"}],"up":[{"embeddable":true,"href":"https:\/\/madridtravelprivatetours.com\/fr\/wp-json\/wp\/v2\/pages\/3967"}],"wp:attachment":[{"href":"https:\/\/madridtravelprivatetours.com\/fr\/wp-json\/wp\/v2\/media?parent=4359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}